{"id":2023,"date":"2019-05-15T16:52:50","date_gmt":"2019-05-15T14:52:50","guid":{"rendered":"https:\/\/ashobbysport.it\/index.php\/tempo-fa-2009\/"},"modified":"2019-05-15T16:56:53","modified_gmt":"2019-05-15T14:56:53","slug":"tempo-fa-2009","status":"publish","type":"page","link":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/","title":{"rendered":"tempo fa &#8211; 2009"},"content":{"rendered":"<p><a href=\"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/\">Torna a: Anni 2006-2010<\/a><\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Torna a: Anni 2006-2010<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":255,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2023","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>tempo fa - 2009 - A.S.D. GINNASTICA HOBBY SPORT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tempo fa - 2009 - A.S.D. GINNASTICA HOBBY SPORT\" \/>\n<meta property=\"og:description\" content=\"Torna a: Anni 2006-2010\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/\" \/>\n<meta property=\"og:site_name\" content=\"A.S.D. GINNASTICA HOBBY SPORT\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T14:56:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/le-foto-della-nostra-storia\\\/anni-2006-2010\\\/tempo-fa-2009\\\/\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/le-foto-della-nostra-storia\\\/anni-2006-2010\\\/tempo-fa-2009\\\/\",\"name\":\"tempo fa - 2009 - A.S.D. GINNASTICA HOBBY SPORT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#website\"},\"datePublished\":\"2019-05-15T14:52:50+00:00\",\"dateModified\":\"2019-05-15T14:56:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/le-foto-della-nostra-storia\\\/anni-2006-2010\\\/tempo-fa-2009\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/le-foto-della-nostra-storia\\\/anni-2006-2010\\\/tempo-fa-2009\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/le-foto-della-nostra-storia\\\/anni-2006-2010\\\/tempo-fa-2009\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ashobbysport.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chi siamo\",\"item\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le foto e i video della nostra storia\",\"item\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/le-foto-della-nostra-storia\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Anni 2006-2010\",\"item\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/chi-siamo\\\/le-foto-della-nostra-storia\\\/anni-2006-2010\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"tempo fa &#8211; 2009\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#website\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/\",\"name\":\"A.S. HOBBY SPORT\",\"description\":\"La Ginnastica elevata a potenza\",\"publisher\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ashobbysport.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#organization\",\"name\":\"A.S.D.G. Hobby Sport\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/hobbysportcolore.jpg\",\"contentUrl\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/hobbysportcolore.jpg\",\"width\":1179,\"height\":571,\"caption\":\"A.S.D.G. Hobby Sport\"},\"image\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"tempo fa - 2009 - A.S.D. GINNASTICA HOBBY SPORT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/","og_locale":"it_IT","og_type":"article","og_title":"tempo fa - 2009 - A.S.D. GINNASTICA HOBBY SPORT","og_description":"Torna a: Anni 2006-2010","og_url":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/","og_site_name":"A.S.D. GINNASTICA HOBBY SPORT","article_modified_time":"2019-05-15T14:56:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/","url":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/","name":"tempo fa - 2009 - A.S.D. GINNASTICA HOBBY SPORT","isPartOf":{"@id":"https:\/\/ashobbysport.it\/#website"},"datePublished":"2019-05-15T14:52:50+00:00","dateModified":"2019-05-15T14:56:53+00:00","breadcrumb":{"@id":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/tempo-fa-2009\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ashobbysport.it\/"},{"@type":"ListItem","position":2,"name":"Chi siamo","item":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/"},{"@type":"ListItem","position":3,"name":"Le foto e i video della nostra storia","item":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/"},{"@type":"ListItem","position":4,"name":"Anni 2006-2010","item":"https:\/\/ashobbysport.it\/index.php\/chi-siamo\/le-foto-della-nostra-storia\/anni-2006-2010\/"},{"@type":"ListItem","position":5,"name":"tempo fa &#8211; 2009"}]},{"@type":"WebSite","@id":"https:\/\/ashobbysport.it\/#website","url":"https:\/\/ashobbysport.it\/","name":"A.S. HOBBY SPORT","description":"La Ginnastica elevata a potenza","publisher":{"@id":"https:\/\/ashobbysport.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ashobbysport.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ashobbysport.it\/#organization","name":"A.S.D.G. Hobby Sport","url":"https:\/\/ashobbysport.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ashobbysport.it\/#\/schema\/logo\/image\/","url":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2018\/01\/hobbysportcolore.jpg","contentUrl":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2018\/01\/hobbysportcolore.jpg","width":1179,"height":571,"caption":"A.S.D.G. Hobby Sport"},"image":{"@id":"https:\/\/ashobbysport.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/pages\/2023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/comments?post=2023"}],"version-history":[{"count":3,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/pages\/2023\/revisions"}],"predecessor-version":[{"id":2027,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/pages\/2023\/revisions\/2027"}],"up":[{"embeddable":true,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/pages\/255"}],"wp:attachment":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/media?parent=2023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}