{"id":3133,"date":"2019-12-09T19:58:40","date_gmt":"2019-12-09T18:58:40","guid":{"rendered":"https:\/\/ashobbysport.it\/?p=3133"},"modified":"2019-12-09T19:58:40","modified_gmt":"2019-12-09T18:58:40","slug":"celebrati-i-150-anni-della-fgi","status":"publish","type":"post","link":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/","title":{"rendered":"Celebrati i 150 anni della FGI"},"content":{"rendered":"<p>Anche in Sicilia, presso il Teatro Garibaldi di Enna, si sono celebrati i 150 anni della nostra Federazione, la Federazione Ginnastica d&#8217;Italia, la prima federazione sportiva nata in Italia.<\/p>\n<p>Tra i riconoscimenti assegnati per l&#8217;occasione, la targa per i 40 anni di attivit\u00e0 della nostra Associazione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3132 size-large\" src=\"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-1024x738.jpg\" alt=\"targa ricordo 150 anni FGI\" width=\"525\" height=\"378\" srcset=\"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-1024x738.jpg 1024w, https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-300x216.jpg 300w, https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-768x554.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nIl riconoscimento \u00e8 stato ricevuto con grande orgoglio dal nostro presidente, Andrea Cianci, dalle mani del Presidente Federale Gherardo Tecchi.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-3134\" src=\"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/IMG-20191129-WA0020-833x1024.jpg\" alt=\"la targa ricordo al presidente Cianci\" width=\"525\" height=\"645\" srcset=\"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/IMG-20191129-WA0020-833x1024.jpg 833w, https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/IMG-20191129-WA0020-244x300.jpg 244w, https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/IMG-20191129-WA0020-768x944.jpg 768w, https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/IMG-20191129-WA0020.jpg 1666w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche in Sicilia, presso il Teatro Garibaldi di Enna, si sono celebrati i 150 anni della nostra Federazione, la Federazione Ginnastica d&#8217;Italia, la prima federazione sportiva nata in Italia. Tra i riconoscimenti assegnati per l&#8217;occasione, la targa per i 40 anni di attivit\u00e0 della nostra Associazione. Il riconoscimento \u00e8 stato ricevuto con grande orgoglio dal &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Celebrati i 150 anni della FGI&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-3133","post","type-post","status-publish","format-standard","hentry","category-palestra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebrati i 150 anni della FGI - A.S.D. GINNASTICA HOBBY SPORT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrati i 150 anni della FGI - A.S.D. GINNASTICA HOBBY SPORT\" \/>\n<meta property=\"og:description\" content=\"Anche in Sicilia, presso il Teatro Garibaldi di Enna, si sono celebrati i 150 anni della nostra Federazione, la Federazione Ginnastica d&#8217;Italia, la prima federazione sportiva nata in Italia. Tra i riconoscimenti assegnati per l&#8217;occasione, la targa per i 40 anni di attivit\u00e0 della nostra Associazione. Il riconoscimento \u00e8 stato ricevuto con grande orgoglio dal &hellip; Leggi tutto &quot;Celebrati i 150 anni della FGI&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/\" \/>\n<meta property=\"og:site_name\" content=\"A.S.D. GINNASTICA HOBBY SPORT\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-09T18:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-1024x738.jpg\" \/>\n<meta name=\"author\" content=\"andy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"andy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/\"},\"author\":{\"name\":\"andy\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#\\\/schema\\\/person\\\/b642a67d804ba1859794dce2dbf38819\"},\"headline\":\"Celebrati i 150 anni della FGI\",\"datePublished\":\"2019-12-09T18:58:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/\"},\"wordCount\":70,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/20191209_194417-e1575917266439-1024x738.jpg\",\"articleSection\":[\"palestra\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/\",\"name\":\"Celebrati i 150 anni della FGI - A.S.D. GINNASTICA HOBBY SPORT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/20191209_194417-e1575917266439-1024x738.jpg\",\"datePublished\":\"2019-12-09T18:58:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/20191209_194417-e1575917266439.jpg\",\"contentUrl\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/20191209_194417-e1575917266439.jpg\",\"width\":2711,\"height\":1955,\"caption\":\"targa ricordo 150 anni FGI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/index.php\\\/2019\\\/12\\\/09\\\/celebrati-i-150-anni-della-fgi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ashobbysport.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrati i 150 anni della FGI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#website\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/\",\"name\":\"A.S. HOBBY SPORT\",\"description\":\"La Ginnastica elevata a potenza\",\"publisher\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ashobbysport.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#organization\",\"name\":\"A.S.D.G. Hobby Sport\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/hobbysportcolore.jpg\",\"contentUrl\":\"https:\\\/\\\/ashobbysport.it\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/hobbysportcolore.jpg\",\"width\":1179,\"height\":571,\"caption\":\"A.S.D.G. Hobby Sport\"},\"image\":{\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ashobbysport.it\\\/#\\\/schema\\\/person\\\/b642a67d804ba1859794dce2dbf38819\",\"name\":\"andy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165eabeb711bd90f375c798c7d568c6b359b582d9bb418760ff7933b069c8d6f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165eabeb711bd90f375c798c7d568c6b359b582d9bb418760ff7933b069c8d6f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165eabeb711bd90f375c798c7d568c6b359b582d9bb418760ff7933b069c8d6f?s=96&d=mm&r=g\",\"caption\":\"andy\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrati i 150 anni della FGI - A.S.D. GINNASTICA HOBBY SPORT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/","og_locale":"it_IT","og_type":"article","og_title":"Celebrati i 150 anni della FGI - A.S.D. GINNASTICA HOBBY SPORT","og_description":"Anche in Sicilia, presso il Teatro Garibaldi di Enna, si sono celebrati i 150 anni della nostra Federazione, la Federazione Ginnastica d&#8217;Italia, la prima federazione sportiva nata in Italia. Tra i riconoscimenti assegnati per l&#8217;occasione, la targa per i 40 anni di attivit\u00e0 della nostra Associazione. Il riconoscimento \u00e8 stato ricevuto con grande orgoglio dal &hellip; Leggi tutto \"Celebrati i 150 anni della FGI\"","og_url":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/","og_site_name":"A.S.D. GINNASTICA HOBBY SPORT","article_published_time":"2019-12-09T18:58:40+00:00","og_image":[{"url":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-1024x738.jpg","type":"","width":"","height":""}],"author":"andy","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"andy"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#article","isPartOf":{"@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/"},"author":{"name":"andy","@id":"https:\/\/ashobbysport.it\/#\/schema\/person\/b642a67d804ba1859794dce2dbf38819"},"headline":"Celebrati i 150 anni della FGI","datePublished":"2019-12-09T18:58:40+00:00","mainEntityOfPage":{"@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/"},"wordCount":70,"commentCount":0,"publisher":{"@id":"https:\/\/ashobbysport.it\/#organization"},"image":{"@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#primaryimage"},"thumbnailUrl":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-1024x738.jpg","articleSection":["palestra"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/","url":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/","name":"Celebrati i 150 anni della FGI - A.S.D. GINNASTICA HOBBY SPORT","isPartOf":{"@id":"https:\/\/ashobbysport.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#primaryimage"},"image":{"@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#primaryimage"},"thumbnailUrl":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439-1024x738.jpg","datePublished":"2019-12-09T18:58:40+00:00","breadcrumb":{"@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#primaryimage","url":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439.jpg","contentUrl":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2019\/12\/20191209_194417-e1575917266439.jpg","width":2711,"height":1955,"caption":"targa ricordo 150 anni FGI"},{"@type":"BreadcrumbList","@id":"https:\/\/ashobbysport.it\/index.php\/2019\/12\/09\/celebrati-i-150-anni-della-fgi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ashobbysport.it\/"},{"@type":"ListItem","position":2,"name":"Celebrati i 150 anni della FGI"}]},{"@type":"WebSite","@id":"https:\/\/ashobbysport.it\/#website","url":"https:\/\/ashobbysport.it\/","name":"A.S. HOBBY SPORT","description":"La Ginnastica elevata a potenza","publisher":{"@id":"https:\/\/ashobbysport.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ashobbysport.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ashobbysport.it\/#organization","name":"A.S.D.G. Hobby Sport","url":"https:\/\/ashobbysport.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ashobbysport.it\/#\/schema\/logo\/image\/","url":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2018\/01\/hobbysportcolore.jpg","contentUrl":"https:\/\/ashobbysport.it\/wp-content\/uploads\/2018\/01\/hobbysportcolore.jpg","width":1179,"height":571,"caption":"A.S.D.G. Hobby Sport"},"image":{"@id":"https:\/\/ashobbysport.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ashobbysport.it\/#\/schema\/person\/b642a67d804ba1859794dce2dbf38819","name":"andy","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165eabeb711bd90f375c798c7d568c6b359b582d9bb418760ff7933b069c8d6f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165eabeb711bd90f375c798c7d568c6b359b582d9bb418760ff7933b069c8d6f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165eabeb711bd90f375c798c7d568c6b359b582d9bb418760ff7933b069c8d6f?s=96&d=mm&r=g","caption":"andy"}}]}},"_links":{"self":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/posts\/3133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/comments?post=3133"}],"version-history":[{"count":1,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/posts\/3133\/revisions"}],"predecessor-version":[{"id":3135,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/posts\/3133\/revisions\/3135"}],"wp:attachment":[{"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/media?parent=3133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/categories?post=3133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ashobbysport.it\/index.php\/wp-json\/wp\/v2\/tags?post=3133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}